{"id":3274,"date":"2025-07-27T16:55:31","date_gmt":"2025-07-27T16:55:31","guid":{"rendered":"https:\/\/kardiologie-nixdorff.de\/?page_id=3274"},"modified":"2026-03-15T10:41:14","modified_gmt":"2026-03-15T10:41:14","slug":"check-up-professional","status":"publish","type":"page","link":"https:\/\/kardiologie-nixdorff.de\/nl\/check-up-professional\/","title":{"rendered":"Professionele controle"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3274\" class=\"elementor elementor-3274\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39bb78c5 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"39bb78c5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24a7cc1e\" data-id=\"24a7cc1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c2accd4 e-flex e-con-boxed e-con e-parent\" data-id=\"c2accd4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-393bb94e e-con-full e-flex e-con e-child\" data-id=\"393bb94e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3dbc1d56 e-flex e-con-boxed e-con e-child\" data-id=\"3dbc1d56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22832819 elementor-widget elementor-widget-heading\" data-id=\"22832819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CHECK-UP Professional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bdb32e elementor-widget elementor-widget-text-editor\" data-id=\"1bdb32e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"font-style: normal; color: #14261c;\">Professional Check-up \u2013 inklusive hochmoderner radiologischer Bildgebung<\/h3><p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #4f5655;\">Der Professional Check-up bietet eine erweiterte Diagnostik mit modernsten Verfahren.\u00a0Diese Leistungen z\u00e4hlen zu den modernsten Pr\u00e4ventionsma\u00dfnahmen und m\u00fcssen in der Regel als\u00a0<span style=\"font-weight: bold;\">Selbstzahlerleistung<\/span>\u00a0in Anspruch genommen werden.<\/p><p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #4f5655;\">\u00a0<\/p><p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #4f5655;\"><span style=\"font-weight: bold;\">Hinweis zur Abrechnung:<\/span><\/p><p style=\"font-size: 16px; font-style: normal; font-weight: 400; color: #4f5655;\">Private Krankenversicherungen \u00fcbernehmen i.d.R. einen Teil der Kosten f\u00fcr unsere Check-ups. Die\u00a0<span style=\"font-weight: bold;\">gesetzlichen Krankenkassen<\/span>\u00a0\u00fcbernehmen diese Kosten leider nicht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21b6b4ef e-grid e-con-boxed e-con e-child\" data-id=\"21b6b4ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5e0d062e e-flex e-con-boxed e-con e-child\" data-id=\"5e0d062e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-36c020d3 e-flex e-con-boxed e-con e-child\" data-id=\"36c020d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6502af24 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6502af24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-Web-Portals\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46e94728 elementor-widget elementor-widget-text-editor\" data-id=\"46e94728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dauer ca. 5 Stunden\u00a0<br \/>Wir versuchen alle Untersuchungen am gleichen Tag durchzuf\u00fchren<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21b2fd39 e-flex e-con-boxed e-con e-child\" data-id=\"21b2fd39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c80ddb9 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7c80ddb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b910e47 elementor-widget elementor-widget-text-editor\" data-id=\"4b910e47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Check-Up mit ausf\u00fchrlicher Anamnese, erweiterten Laboruntersuchungen und hochmoderner radiologischer Bildgebung nach Indikation<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-599b4bd8 e-flex e-con-boxed e-con e-child\" data-id=\"599b4bd8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65d26f26 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"65d26f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-book1\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8612909 elementor-widget elementor-widget-text-editor\" data-id=\"8612909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Am Ende des Check-Ups erhalten Sie eine ausf\u00fchrliche Befundmappe<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20eca101 e-flex e-con-boxed e-con e-parent\" data-id=\"20eca101\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-442eb5b2 e-con-full e-flex e-con e-child\" data-id=\"442eb5b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7ffe0bf0 e-flex e-con-boxed e-con e-child\" data-id=\"7ffe0bf0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65e60828 elementor-widget elementor-widget-heading\" data-id=\"65e60828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcbersicht der Check-Up Inhalte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e949fe8 elementor-widget elementor-widget-accordion\" data-id=\"5e949fe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1581\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1581\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">PreCheck<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1581\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1581\"><p>Aktuelle ausf\u00fchrliche Anamnese und Vorgeschichte &#8211; Im Rahmen der Anamnese:<\/p><ul><li>Bei Nikotinabh\u00e4ngigkeit: Frageinventar zur k\u00f6rperlichen Nikotinabh\u00e4ngigkeit als Grundlage zur Raucherentw\u00f6hnung (Fagerstr\u00f6m-Test)<\/li><li>Standardisiertes Frageinventar zum Wohlbefinden <br \/>nach WHO als Grundlage f\u00fcr Lebensstilberatung<\/li><li>Risikofaktoren-Analyse (PROCAM-Score)<\/li><li>Anthropometrie inkl. Bioimpedanzanalysemessungen <br \/>&#8211; Berechnung des Body Mass Index (BMI) <br \/>&#8211; Berechnung des Taillen- und H\u00fcftumfangs [waist-to-hip- ratio (WHR), waist-to- height ratio (WHtR)]<br \/>&#8211; K\u00f6rperzusammensetzung (Fett, Wasser, Biomasse).<\/li><li>Sauerstoffs\u00e4ttigung (Pulsoxymetrie)<\/li><li>Eingehende k\u00f6rperliche Untersuchung<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1582\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1582\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Labormedizinische Untersuchungen<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1582\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1582\"><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Differentialblutbild (gro\u00dfes Blutbild) inkl. Differenzierung des wei\u00dfen Blutbildes<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Blutzuckerwerte:\u00a0 N\u00fcchtern-Blutzucker, HbA1c Basalinsulin (inkl. HOMA-Index)<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cholesterinstatus: Gesamtcholesterin, HDL-, LDL-Cholesterin und Triglyceride<br \/>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Apolipoprotein B<br \/>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Apolipoprotein A1<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Leber-\/Gallewerte-\/Bauchspeicheldr\u00fcsenwerte: Gamma-GT, GOT, GPT, LDH, Cholinesterase, Bilirubin, Lipase, Amylase, alkalische Phosphatase<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nierenwerte: Creatintin, Harnstoff, Harns\u00e4ure<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Muskulatur: Creatinkinase<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Elektrolyte\/Stoffwechsel: Calcium, Chlorid, Kalium, Natrium, Magnesium, Ferritin<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Gerinnungswerte: INR (Quick), PTT, Fibrinogen<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0APC-Resistenz<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Eiwei\u00dfanalyse: Eiwei\u00df gesamt und Eiwei\u00dfelektrophorese<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Schilddr\u00fcsenhormonstatus: TSH basal (LIA)<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0fT3, fT4<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Urinstatus: pH-Wert, Leukozyten, Eiwei\u00df, Glucose, Keton, Erythrozyten, Urobilinogen, Nitrit, Dichte, Bilirubin; inklusive Micraltest (Mikroalbumin)<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Stuhluntersuchung: ScheBo\u00ae o 2in1 Quick\u2122 Stuhltest\u00a0 (immunologischer Stuhltest)<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Blasenkarzinom-Screening: \u00a0NMP22\u00ae BladderChek\u00ae Urin-Test zur Blasenkrebsvorsorge (immunologischer <br \/>Urintest)<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 emerging risk factors: high sensitive CRP, Lipoprotein(a), Homocystein<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Arterielle Plaque-Aktivit\u00e4t: &#8211; Lipoprotein-assoziierte Phospholipase A2 (Lp- PLA2)<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Kardiale Marker: NT-proBNP<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Omega-3-Index<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Vitamin D (25-Hydrox-Vitamin D)<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Immunoglobuline: IgA, IgG, IgM, IgE<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 M\u00e4nner-Labor (bei M\u00e4nnern ab dem 40. Lebensjahr): PSA \/ ggf. freies PSA<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Testosteron<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Sexualhormon-bindendes Globulin (SHBG) mit Errechnung des Androgenindex<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1583\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1583\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Instrumentelle Untersuchung der Organe und Gef\u00e4\u00dfe<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1583\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1583\"><p style=\"font-size: 16px; font-style: normal; font-weight: 400;\"><span style=\"font-style: inherit; font-weight: inherit;\">&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Echokardiographie inkl. Gewebe-Doppler<\/span><\/p><p style=\"font-size: 16px; font-style: normal; font-weight: 400;\"><span style=\"font-size: 1rem;\">&#8211;\u00a0 \u00a0<\/span><span style=\"font-style: inherit; font-weight: inherit;\">\u00a0\u00a0 \u00a0 \u00a0 \u00a0Duplex-Sonographie der Halsschlagadern inkl. alters- und geschlechtsadjustierter Intima-Media- Dickenmessung<\/span><\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sonographie der Schilddr\u00fcse<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1584\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1584\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Fitness-Assessment (Herz-Kreislauf-Check)<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1584\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1584\"><p style=\"font-size: 16px; font-style: normal; font-weight: 400;\">&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a012-Kanal EKG \/ Ruhe-EKG<\/p><p style=\"font-size: 16px; font-style: normal; font-weight: 400;\"><span style=\"font-style: inherit; font-weight: inherit;\">&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Lungenfunktion<\/span><\/p><p style=\"font-size: 16px; font-style: normal; font-weight: 400;\"><span style=\"font-style: inherit; font-weight: inherit;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pulswellenanalyse inkl. Ermittlung des ABI-Index (Kn\u00f6chel-Arm-Index)<\/span><\/p><p><span style=\"font-style: inherit; font-weight: inherit;\">&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Herzratenvariabilit\u00e4t (HRV) zur Erfassung des\u00a0 psychosomatischen Stressniveaus<\/span><\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Gewebe-Doppler-Echokardiographie (TDE)<\/p><p><span style=\"font-style: inherit; font-weight: inherit;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Doppler-Echokardiographie \/ STRAIN-Analyse<\/span><\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pulswellenanalyse inkl. Ermittlung des ABI-Index (Kn\u00f6chel-Arm-Index)<\/p><p>&#8211;\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<span style=\"font-size: 1rem;\">Ergospirometrie<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1585\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1585\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Abschlussgespr\u00e4ch \/ Befundmappe<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1585\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1585\"><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ausf\u00fchrliches Abschlussgespr\u00e4ch, Illustration und Interpretation s\u00e4mtlicher bildgebender Befunde<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lebensstilberatung, auf individuellen Befund abgestellt<\/p><p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Schriftlicher allgemein verst\u00e4ndlicher Abschlussbericht<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-630f563b elementor-widget elementor-widget-text-editor\" data-id=\"630f563b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW45689533 BCX8\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">Bitte beachten Sie, dass der Tagesablauf sowie die Art der Untersuchungen &#8211; abh\u00e4ngig von Ihren individuellen<\/span> <span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">Risikofaktoren<\/span> <span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">und<\/span> <span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">W\u00fcnschen<\/span> <span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">&#8211;<\/span> <span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">mehr oder weniger von<\/span> <span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">diesem Beispiel abweichen<\/span> <span class=\"NormalTextRun SCXW45689533 BCX8\" data-ccp-parastyle=\"Body Text\">k\u00f6nnen.<\/span><\/span><span class=\"EOP SCXW45689533 BCX8\" data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:0,&quot;335559685&quot;:220,&quot;335559737&quot;:824,&quot;335559740&quot;:324}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aed9ddd elementor-widget elementor-widget-n-accordion\" data-id=\"aed9ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1830\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1830\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Weitere Zusatzleistungen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1830\" class=\"elementor-element elementor-element-2b394e1 e-con-full e-flex e-con e-child\" data-id=\"2b394e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f214b6e elementor-widget elementor-widget-text-editor\" data-id=\"f214b6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWeitere Untersuchungen k\u00f6nnen je nach Indikation erfolgen:\n<li>hochmoderne radiologische Bildgebung nach Indikationsstellung<\/li>\n \t<li>oraler Glukosetoleranztest (oGTT)<\/li>\n \t<li>Holter-EKG (bei Rhythmusst\u00f6rungen)<\/li>\n \t<li>Ambulantes Blutdruck-Monitoring (ABDM) (bei Bluthochdruck)<\/li>\n \t<li>Schlaf-Apnoe-Screening<\/li>\n \t<li>Dynamisches Stress-Echo<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91e5273 e-flex e-con-boxed e-con e-parent\" data-id=\"91e5273\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33179936 elementor-widget elementor-widget-heading\" data-id=\"33179936\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sie m\u00f6chten einen Termin vereinbaren?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60641c82 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"60641c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1332adaa e-flex e-con-boxed e-con e-child\" data-id=\"1332adaa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bfa1b41 e-flex e-con-boxed e-con e-child\" data-id=\"bfa1b41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-465df62c elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"465df62c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-683x1024.jpg\" class=\"attachment-large size-large wp-image-1594\" alt=\"\" srcset=\"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-683x1024.jpg 683w, https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-200x300.jpg 200w, https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-768x1152.jpg 768w, https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-1024x1536.jpg 1024w, https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-1366x2048.jpg 1366w, https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85c5ba0 e-flex e-con-boxed e-con e-child\" data-id=\"85c5ba0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-374ba6c8 elementor-widget elementor-widget-text-editor\" data-id=\"374ba6c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser Praxisteam unter der Leitung von Frau Guderjahn steht Ihnen gerne zur Verf\u00fcgung. Rufen Sie einfach w\u00e4hrend unserer Praxiszeiten an, schreiben Sie uns eine E-Mail oder nutzen Sie unser Kontaktformular.<\/p><p>\u00a0<\/p><p>Telefon: +49 211 838 628 50<\/p><p>\u00a0<\/p><p><strong>E-Mail:\u00a0<a href=\"mailto:info@kardiologie-nixdorff.de\">info@kardiologie-nixdorff.de<\/a><\/strong><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-203e6a1f elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"203e6a1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktformular<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CHECK-UP Professional Professional Check-up \u2013 inklusive hochmoderner radiologischer Bildgebung Der Professional Check-up bietet eine erweiterte Diagnostik mit modernsten Verfahren.\u00a0Diese Leistungen z\u00e4hlen zu den modernsten Pr\u00e4ventionsma\u00dfnahmen und m\u00fcssen in der Regel als\u00a0Selbstzahlerleistung\u00a0in Anspruch genommen werden. \u00a0 Hinweis zur Abrechnung: Private Krankenversicherungen \u00fcbernehmen i.d.R. einen Teil der Kosten f\u00fcr unsere Check-ups. Die\u00a0gesetzlichen Krankenkassen\u00a0\u00fcbernehmen diese Kosten leider nicht. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3274","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Professional Check-Up - Kardiologische Privatpraxis - Prof. Nixdorff<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kardiologie-nixdorff.de\/nl\/check-up-professional\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professional Check-Up\" \/>\n<meta property=\"og:description\" content=\"CHECK-UP Professional Professional Check-up \u2013 inklusive hochmoderner radiologischer Bildgebung Der Professional Check-up bietet eine erweiterte Diagnostik mit modernsten Verfahren.\u00a0Diese Leistungen z\u00e4hlen zu den modernsten Pr\u00e4ventionsma\u00dfnahmen und m\u00fcssen in der Regel als\u00a0Selbstzahlerleistung\u00a0in Anspruch genommen werden. \u00a0 Hinweis zur Abrechnung: Private Krankenversicherungen \u00fcbernehmen i.d.R. einen Teil der Kosten f\u00fcr unsere Check-ups. Die\u00a0gesetzlichen Krankenkassen\u00a0\u00fcbernehmen diese Kosten leider nicht. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kardiologie-nixdorff.de\/nl\/check-up-professional\/\" \/>\n<meta property=\"og:site_name\" content=\"Kardiologische Privatpraxis - Prof. Nixdorff\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-15T10:41:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/\",\"url\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/\",\"name\":\"Professional Check-Up - Kardiologische Privatpraxis - Prof. Nixdorff\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/IMG_7681-scaled-1-683x1024.jpg\",\"datePublished\":\"2025-07-27T16:55:31+00:00\",\"dateModified\":\"2026-03-15T10:41:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/IMG_7681-scaled-1-683x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/IMG_7681-scaled-1-683x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/check-up-professional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professional Check-Up\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/#website\",\"url\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/\",\"name\":\"Kardiologische Privatpraxis - Prof. Nixdorff\",\"description\":\"Die Kardiologische Privatpraxis Nixdorff &amp; Vester in D&uuml;sseldorf bietet spezialisierte kardiologische Behandlungen mit einem ganzheitlichen Ansatz. Geleitet von den erfahrenen Kardiologen Prof. Dr. med. Uwe Nixdorff und Prof. Dr. med. Ernst G. Vester, verbindet die Praxis pr&auml;ventive und interventionelle Medizin. Das Team bietet individuelle Diagnostik und Betreuung f&uuml;r Herzgesundheit, von Erstuntersuchungen bis zu komplexen F&auml;llen. Patienten profitieren zudem von der Anbindung an das European Prevention Center f&uuml;r umfassende Gesundheits-Check-ups. Die Praxis ist nur f&uuml;r privat versicherte Patienten oder Selbstzahler zug&auml;nglich.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/#organization\"},\"alternateName\":\"Kardiologie D\u00fcsseldorf\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/#organization\",\"name\":\"Kardiologische Privatpraxis - Prof. Nixdorff\",\"url\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Logo_Kardiologie.jpg\",\"contentUrl\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Logo_Kardiologie.jpg\",\"width\":512,\"height\":512,\"caption\":\"Kardiologische Privatpraxis - Prof. Nixdorff\"},\"image\":{\"@id\":\"https:\\\/\\\/kardiologie-nixdorff.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Professionele check-up - cardiologische priv\u00e9praktijk - Prof. Nixdorff","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kardiologie-nixdorff.de\/nl\/check-up-professional\/","og_locale":"nl_NL","og_type":"article","og_title":"Professional Check-Up","og_description":"CHECK-UP Professional Professional Check-up \u2013 inklusive hochmoderner radiologischer Bildgebung Der Professional Check-up bietet eine erweiterte Diagnostik mit modernsten Verfahren.\u00a0Diese Leistungen z\u00e4hlen zu den modernsten Pr\u00e4ventionsma\u00dfnahmen und m\u00fcssen in der Regel als\u00a0Selbstzahlerleistung\u00a0in Anspruch genommen werden. \u00a0 Hinweis zur Abrechnung: Private Krankenversicherungen \u00fcbernehmen i.d.R. einen Teil der Kosten f\u00fcr unsere Check-ups. Die\u00a0gesetzlichen Krankenkassen\u00a0\u00fcbernehmen diese Kosten leider nicht. [&hellip;]","og_url":"https:\/\/kardiologie-nixdorff.de\/nl\/check-up-professional\/","og_site_name":"Kardiologische Privatpraxis - Prof. Nixdorff","article_modified_time":"2026-03-15T10:41:14+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"3 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kardiologie-nixdorff.de\/check-up-professional\/","url":"https:\/\/kardiologie-nixdorff.de\/check-up-professional\/","name":"Professionele check-up - cardiologische priv\u00e9praktijk - Prof. Nixdorff","isPartOf":{"@id":"https:\/\/kardiologie-nixdorff.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kardiologie-nixdorff.de\/check-up-professional\/#primaryimage"},"image":{"@id":"https:\/\/kardiologie-nixdorff.de\/check-up-professional\/#primaryimage"},"thumbnailUrl":"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-683x1024.jpg","datePublished":"2025-07-27T16:55:31+00:00","dateModified":"2026-03-15T10:41:14+00:00","breadcrumb":{"@id":"https:\/\/kardiologie-nixdorff.de\/check-up-professional\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kardiologie-nixdorff.de\/check-up-professional\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/kardiologie-nixdorff.de\/check-up-professional\/#primaryimage","url":"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-683x1024.jpg","contentUrl":"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2023\/07\/IMG_7681-scaled-1-683x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/kardiologie-nixdorff.de\/check-up-professional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kardiologie-nixdorff.de\/"},{"@type":"ListItem","position":2,"name":"Professional Check-Up"}]},{"@type":"WebSite","@id":"https:\/\/kardiologie-nixdorff.de\/#website","url":"https:\/\/kardiologie-nixdorff.de\/","name":"Cardiologische priv\u00e9praktijk - Prof. Nixdorff","description":"De cardiologische priv\u00e9praktijk Nixdorff &amp; Vester in D\u00fcsseldorf biedt gespecialiseerde cardiologische behandelingen met een holistische benadering. Onder leiding van de ervaren cardiologen Prof. Dr. Uwe Nixdorff en Prof. Dr. Ernst G. Vester combineert de praktijk preventieve en interventiegeneeskunde. Het team biedt ge\u00efndividualiseerde diagnostiek en zorg voor de gezondheid van het hart, van eerste onderzoeken tot complexe gevallen. Pati\u00ebnten profiteren ook van de verbinding met het Europees Preventiecentrum voor uitgebreide gezondheidscontroles. De praktijk is alleen toegankelijk voor particulier verzekerde pati\u00ebnten of pati\u00ebnten die zelf betalen.","publisher":{"@id":"https:\/\/kardiologie-nixdorff.de\/#organization"},"alternateName":"Kardiologie D\u00fcsseldorf","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kardiologie-nixdorff.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/kardiologie-nixdorff.de\/#organization","name":"Cardiologische priv\u00e9praktijk - Prof. Nixdorff","url":"https:\/\/kardiologie-nixdorff.de\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/kardiologie-nixdorff.de\/#\/schema\/logo\/image\/","url":"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2025\/10\/cropped-Logo_Kardiologie.jpg","contentUrl":"https:\/\/kardiologie-nixdorff.de\/wp-content\/uploads\/2025\/10\/cropped-Logo_Kardiologie.jpg","width":512,"height":512,"caption":"Kardiologische Privatpraxis - Prof. Nixdorff"},"image":{"@id":"https:\/\/kardiologie-nixdorff.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/pages\/3274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/comments?post=3274"}],"version-history":[{"count":30,"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/pages\/3274\/revisions"}],"predecessor-version":[{"id":3621,"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/pages\/3274\/revisions\/3621"}],"wp:attachment":[{"href":"https:\/\/kardiologie-nixdorff.de\/nl\/wp-json\/wp\/v2\/media?parent=3274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}